{"id":3593,"date":"2026-05-12T13:03:42","date_gmt":"2026-05-12T13:03:42","guid":{"rendered":"https:\/\/literalmex.com\/?p=3593"},"modified":"2026-05-12T13:23:12","modified_gmt":"2026-05-12T13:23:12","slug":"marina-protegio-a-los-farias-almirantes-huachicoleros-sobrinos-de-rafael-ojeda-fgr","status":"publish","type":"post","link":"https:\/\/literalmex.com\/index.php\/2026\/05\/12\/marina-protegio-a-los-farias-almirantes-huachicoleros-sobrinos-de-rafael-ojeda-fgr\/","title":{"rendered":"Marina protegi\u00f3 a los Far\u00edas almirantes huachicoleros sobrinos de Rafael Ojeda: FGR"},"content":{"rendered":"\n<p>La investigaci\u00f3n de la <strong>Fiscal\u00eda General de la Rep\u00fablica (FGR)<\/strong> sobre una red de <strong>huachicol fiscal<\/strong> en las Aduanas mexicanas comenz\u00f3 a exhibir posibles nexos de protecci\u00f3n institucional dentro de la propia <strong>Secretar\u00eda de Marina (Semar)<\/strong>, al se\u00f1alar que el <strong>Vicealmirante Manuel Roberto Far\u00edas Laguna<\/strong> y su hermano, el <strong>Contralmirante Fernando Far\u00edas Laguna<\/strong>, gozaban de respaldo derivado de su parentesco con el entonces titular de la dependencia, <strong>Rafael Ojeda Dur\u00e1n<\/strong> en el sexenio de <strong>Andr\u00e9s Manuel L\u00f3pez Obrador<\/strong>.<\/p>\n\n\n\n<p>Aunque la FGR de <strong>Ernestina Godoy<\/strong> no le atribuye formalmente calidad de imputado al ex Secretario de Marina, su nombre aparece dentro de la solicitud de orden de aprehensi\u00f3n presentada contra 15 empresarios, agentes aduanales y operadores vinculados al presunto esquema de contrabando de hidrocarburos. El documento judicial sostiene que la red criminal ten\u00eda capacidad de infiltraci\u00f3n en puertos, aduanas y estructuras de seguridad federal, seg\u00fan informe del prestigiado periodista <strong>Abel Barajas<\/strong> publicado este martes en el peri\u00f3dico <strong>Reforma<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u00a1INCREIBLE! SHEINBAUM DICE QUE NO SE EST\u00c1 INVESTIGANDO AL ALMIRANTE RAFAEL OJEDA por huachicol fiscal<br><br>Que la Fiscal\u00eda <a href=\"https:\/\/twitter.com\/FGRMexico?ref_src=twsrc%5Etfw\">@FGRMexico<\/a>  de Ernestina Godoy NO encuentra pruebas para vincularlos a proceso, sin embargo, su sobrino Manuel Far\u00edas Laguna encabezaba una estructura de\u2026 <a href=\"https:\/\/t.co\/XrPI6D6VqU\">pic.twitter.com\/XrPI6D6VqU<\/a><\/p>&mdash; Literal M\u00e9xico (@literalmexico) <a href=\"https:\/\/twitter.com\/literalmexico\/status\/2032144200486306037?ref_src=twsrc%5Etfw\">March 12, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Uno de los puntos m\u00e1s delicados de la indagatoria gira alrededor del asesinato del <strong>Contralmirante Fernando Rub\u00e9n Guerrero Alc\u00e1ntar<\/strong>, ejecutado el 8 de noviembre de 2024 en <strong>Manzanillo, Colima<\/strong>, luego de que presuntamente preparaba denuncias relacionadas con las operaciones de los hermanos Far\u00edas Laguna.<\/p>\n\n\n\n<p>La FGR sostiene que el mando naval hab\u00eda informado previamente a personal de la Marina sobre sus movimientos y periodo vacacional, lo que habr\u00eda facilitado su localizaci\u00f3n. En el expediente, la dependencia afirma que: <em>&#8220;Dicha informaci\u00f3n s\u00f3lo era del conocimiento de personal de la Secretar\u00eda de Marina, circunstancia que facilit\u00f3 su ubicaci\u00f3n y posterior ejecuci\u00f3n, con la evidente finalidad de silenciarlo y evitar que se hiciera p\u00fablica la estructura, operaci\u00f3n y protecci\u00f3n institucional de la red de huachicol fiscal liderada por los hermanos Far\u00edas Laguna, quienes contaban con protecci\u00f3n derivada de su parentesco con el entonces Almirante Ojeda Dur\u00e1n&#8221;<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">&quot;SE TIENE QUE INVESTIGAR A L\u00d3PEZ OBRADOR Y AL ALMIRANTE OJEDA POR HUACHICOL&quot; dice el abogado de los marinos implicados y detenidos<br><br>&quot;Las decisiones bajo investigaci\u00f3n s\u00f3lo pod\u00edan autorizarse desde el m\u00e1s alto nivel&quot;: asegur\u00f3 Epigmenio Mendieta, abogado defensor de exmarinos\u2026 <a href=\"https:\/\/t.co\/C4qCM6YEkp\">pic.twitter.com\/C4qCM6YEkp<\/a><\/p>&mdash; Literal M\u00e9xico (@literalmexico) <a href=\"https:\/\/twitter.com\/literalmexico\/status\/2014737898398961690?ref_src=twsrc%5Etfw\">January 23, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>La acusaci\u00f3n coloca nuevamente bajo presi\u00f3n a la administraci\u00f3n federal de <strong>Claudia Sheinbaum<\/strong>, debido a que el caso conecta una trama de corrupci\u00f3n aduanera con mandos de alto nivel de la Marina, instituci\u00f3n que durante el sexenio pasado ampli\u00f3 significativamente su control sobre puertos, recintos fiscales y operaciones estrat\u00e9gicas del Estado mexicano.<\/p>\n\n\n\n<p>El expediente tambi\u00e9n revela sospechas de la Fiscal\u00eda sobre otras muertes relacionadas con el caso. La dependencia considera posible que existiera un <strong>\u201cajuste de cuentas\u201d<\/strong> detr\u00e1s de los fallecimientos de los capitanes <strong>Abraham Jerem\u00edas P\u00e9rez Ram\u00edrez<\/strong> y <strong>Adri\u00e1n Omar del \u00c1ngel Z\u00fa\u00f1iga<\/strong>, oficialmente reportados como suicidio y accidente, respectivamente, tras el estallido del esc\u00e1ndalo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">A PESAR DE CORRUPCI\u00d3N Y HUACHICOL SEGUIR\u00c1N LOS MILITARES EN ADUANAS, dice Claudia Sheinbaum<br><br>La presidenta jura que se acab\u00f3 la impunidad, a pesar del mayor saqueo al pa\u00eds con contrabando de hidrocarburos desde la Marina <br><br>El almirante Rafael Ojeda ni siquiera ha sido llamado a\u2026 <a href=\"https:\/\/t.co\/gVL1hO0G4N\">pic.twitter.com\/gVL1hO0G4N<\/a><\/p>&mdash; Literal M\u00e9xico (@literalmexico) <a href=\"https:\/\/twitter.com\/literalmexico\/status\/1975613058757103708?ref_src=twsrc%5Etfw\">October 7, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>En el caso de P\u00e9rez Ram\u00edrez, la FGR asegura que era investigado por recibir presuntamente un soborno de 100 mil pesos para permitir el ingreso ilegal de combustibles por la Aduana de <strong>Tampico<\/strong>. El oficial muri\u00f3 el 8 de septiembre pasado dentro de oficinas de la Unidad Portuaria de <strong>Altamira<\/strong>, en un hecho clasificado oficialmente como suicidio.<\/p>\n\n\n\n<p>La Fiscal\u00eda advierte en su solicitud judicial que la organizaci\u00f3n investigada operaba mediante amenazas, sobornos y violencia extrema. <em>&#8220;Quedan evidenciados los alcances, capacidad de corrupci\u00f3n y alto nivel de violencia utilizados por los integrantes de esta empresa criminal, quienes de manera reiterada amenazan, coaccionan y privan de la vida a personas que no acatan sus instrucciones o que proporcionan informaci\u00f3n sobre el modus operandi de la organizaci\u00f3n&#8221;<\/em>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">GOLPES DE SHEINBAUM A JAVIER MILEI atoran repatriaci\u00f3n del Contralmirante Fernando Far\u00edas, sobrino del almirante Ojeda, detenido en Argentina por red de huachicol <br><br>El caso se complica tras el respaldo de Sheinbaum a Cristina Kirchner en Barcelona, adversaria de Milei, lo que\u2026 <a href=\"https:\/\/t.co\/hRzB4PTcp0\">pic.twitter.com\/hRzB4PTcp0<\/a><\/p>&mdash; Literal M\u00e9xico (@literalmexico) <a href=\"https:\/\/twitter.com\/literalmexico\/status\/2048102238741295461?ref_src=twsrc%5Etfw\">April 25, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>El caso tambi\u00e9n exhibe las tensiones internas dentro de la Marina tras el relevo de mandos entre <strong>Rafael Ojeda Dur\u00e1n<\/strong> y el actual Secretario, <strong>Raymundo Morales<\/strong>, en un contexto donde el Gobierno federal ha intentado contener el impacto pol\u00edtico de las investigaciones sobre contrabando de combustibles y corrupci\u00f3n aduanera.<\/p>\n\n\n\n<p>A pesar de la gravedad de los se\u00f1alamientos, la Presidenta <strong>Claudia Sheinbaum<\/strong> asegur\u00f3 el pasado 19 de febrero que no exist\u00eda ninguna l\u00ednea de investigaci\u00f3n contra <strong>Ojeda Dur\u00e1n<\/strong>. Sin embargo, la narrativa de la propia FGR abre una ruta de cuestionamientos sobre hasta d\u00f3nde alcanzaba la protecci\u00f3n pol\u00edtica y operativa que, seg\u00fan la acusaci\u00f3n, permiti\u00f3 durante a\u00f1os el funcionamiento de la red de huachicol fiscal dentro de instalaciones estrat\u00e9gicas del pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda sostiene que los hermanos Far\u00edas Laguna operaban una estructura de contrabando de combustibles protegida por v\u00ednculos familiares con el entonces Secretario de Marina, Rafael Ojeda Dur\u00e1n. El caso incluye asesinatos, presuntos ajustes de cuentas y denuncias silenciadas dentro de la propia Semar.<\/p>\n","protected":false},"author":1,"featured_media":3594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[9,8],"tags":[678,1172,758,48,129,694,80,674,55,116,406,969,201],"class_list":["post-3593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","category-noticias","tag-abraham-jeremias-perez-ramirez","tag-adrian-omar-del-angel-zuniga","tag-almirante-rafael-ojeda","tag-andres-manuel-lopez-obrador","tag-claudia-sheinbaum","tag-contralmirante-fernando-farias-laguna","tag-ernestina-godoy","tag-fernando-ruben-guerrero-alcantar","tag-fgr","tag-fiscalia","tag-huachicol","tag-manuel-roberto-farias-laguna","tag-marina"],"_links":{"self":[{"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/posts\/3593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/comments?post=3593"}],"version-history":[{"count":3,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/posts\/3593\/revisions"}],"predecessor-version":[{"id":3599,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/posts\/3593\/revisions\/3599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/media\/3594"}],"wp:attachment":[{"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/media?parent=3593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/categories?post=3593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/tags?post=3593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}