{"id":3600,"date":"2026-05-13T12:37:02","date_gmt":"2026-05-13T12:37:02","guid":{"rendered":"https:\/\/literalmex.com\/?p=3600"},"modified":"2026-05-13T12:40:12","modified_gmt":"2026-05-13T12:40:12","slug":"politicos-mexicanos-en-la-mira-de-la-dea-no-solo-rocha-moya-y-10-extraditables","status":"publish","type":"post","link":"https:\/\/literalmex.com\/index.php\/2026\/05\/13\/politicos-mexicanos-en-la-mira-de-la-dea-no-solo-rocha-moya-y-10-extraditables\/","title":{"rendered":"Pol\u00edticos mexicanos en la mira de la DEA, no s\u00f3lo Rocha Moya y 10 extraditables"},"content":{"rendered":"\n<p>La declaraci\u00f3n del jefe de la <strong>DEA<\/strong>, <strong>Terry Cole<\/strong>, ante el Senado de Estados Unidos, no s\u00f3lo coloc\u00f3 nuevamente en el centro de la discusi\u00f3n al Gobernador con licencia de <strong>Sinaloa<\/strong>, <strong>Rub\u00e9n Rocha Moya<\/strong> y 9 m\u00e1s en la lista de extraditables que pidi\u00f3 la Corte del Distrito Sur de Nueva York, sino que dej\u00f3 entrever un cambio de estrategia en Washington: pasar de perseguir exclusivamente a las organizaciones criminales a enfocar las investigaciones en las estructuras pol\u00edticas que presuntamente les brindan protecci\u00f3n institucional.<\/p>\n\n\n\n<p>Durante una comparecencia ante legisladores estadounidenses, y al responder cuestionamientos del senador republicano por Luisiana, <strong>John Kennedy<\/strong>, Cole asegur\u00f3 que existe una responsabilidad compartida entre narcotraficantes y funcionarios mexicanos acusados de colaborar con el crimen organizado. <em>\u201cNo cabe duda de que los narcotraficantes y altos funcionarios del Gobierno mexicano han estado involucrados durante a\u00f1os, pero ahora de repente le estamos prestando atenci\u00f3n a esto\u201d<\/em>, declar\u00f3 el funcionario estadounidense al referirse al proceso judicial abierto contra Rocha Moya por presuntamente favorecer al <strong>C\u00e1rtel de Sinaloa<\/strong>.<\/p>\n\n\n\n<p>Las declaraciones se producen apenas semanas despu\u00e9s de que el <strong>Departamento de Justicia de Estados Unidos<\/strong> y la propia <strong>DEA<\/strong> anunciaran, el pasado 29 de abril, la primera acusaci\u00f3n formal por narcotr\u00e1fico contra un gobernador mexicano en funciones, junto con otros nueve funcionarios y ex funcionarios sinaloenses. El caso deton\u00f3 una crisis pol\u00edtica en <strong>Sinaloa<\/strong>, donde adem\u00e1s se han multiplicado las presiones sobre integrantes del c\u00edrculo pol\u00edtico cercano al mandatario con licencia.<\/p>\n\n\n\n<p>Cole endureci\u00f3 a\u00fan m\u00e1s el mensaje al sostener que los funcionarios que colaboran con las organizaciones criminales son responsables directos de la crisis de sobredosis por fentanilo en Estados Unidos. <em>\u201cTenemos un Presidente que apoya plenamente a EU, que pone a los estadounidenses primero. (Los pol\u00edticos en M\u00e9xico) son igualmente responsables de la muerte y destrucci\u00f3n de una cantidad r\u00e9cord de estadounidenses al cooperar, conspirar y ayudar a producir este veneno para que cruce la frontera\u201d<\/em>, afirm\u00f3.<\/p>\n\n\n\n<p>La frase que encendi\u00f3 las alertas diplom\u00e1ticas lleg\u00f3 al final de su intervenci\u00f3n. <em>\u201cY le aseguro que esto es s\u00f3lo el comienzo de lo que est\u00e1 por venir en M\u00e9xico\u201d<\/em>, sentenci\u00f3 el titular de la DEA, en lo que fue interpretado como un adelanto de nuevas investigaciones y posibles acciones judiciales contra actores pol\u00edticos mexicanos presuntamente relacionados con los c\u00e1rteles.<\/p>\n\n\n\n<p>Las declaraciones ocurren en medio de una creciente presi\u00f3n de la Administraci\u00f3n de <strong>Donald Trump<\/strong> hacia M\u00e9xico en materia de seguridad, narcotr\u00e1fico y combate al fentanilo. En semanas recientes, Washington endureci\u00f3 el discurso sobre la infiltraci\u00f3n criminal en instituciones mexicanas y condicion\u00f3 parte de la cooperaci\u00f3n bilateral a resultados concretos en extradiciones, detenciones y desmantelamiento de redes de protecci\u00f3n pol\u00edtica.<\/p>\n\n\n\n<p>El caso de <strong>Rub\u00e9n Rocha Moya<\/strong> se convirti\u00f3 as\u00ed en un punto de inflexi\u00f3n en la relaci\u00f3n bilateral. Para sectores pol\u00edticos y de seguridad en Estados Unidos, el expediente abierto contra el mandatario sinaloense representa una se\u00f1al de que las investigaciones ya no se limitar\u00e1n a l\u00edderes criminales, sino que buscar\u00e1n alcanzar a funcionarios acusados de facilitar operaciones financieras, log\u00edsticas o de protecci\u00f3n territorial para los c\u00e1rteles mexicanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El jefe de la DEA, Terry Cole, asegur\u00f3 ante el Senado de EU que funcionarios mexicanos coludidos con el crimen organizado, no s\u00f3lo Rocha Moya, son \u201cigualmente responsables\u201d de la crisis de fentanilo y las muertes por sobredosis.<\/p>\n","protected":false},"author":1,"featured_media":3603,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[9,8],"tags":[286,129,503,407,514,962,692],"class_list":["post-3600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","category-noticias","tag-cartel-de-sinaloa","tag-claudia-sheinbaum","tag-dea","tag-eeuu","tag-fentanilo","tag-rocha-moya","tag-terry-cole"],"_links":{"self":[{"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/posts\/3600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/comments?post=3600"}],"version-history":[{"count":1,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/posts\/3600\/revisions"}],"predecessor-version":[{"id":3602,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/posts\/3600\/revisions\/3602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/media\/3603"}],"wp:attachment":[{"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/media?parent=3600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/categories?post=3600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/tags?post=3600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}