{"id":1155,"count":1,"description":"","link":"https:\/\/literalmex.com\/index.php\/tag\/secretaria-de-administracion-y-finanzas\/","name":"Secretar\u00eda de Administraci\u00f3n y Finanzas","slug":"secretaria-de-administracion-y-finanzas","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/tags\/1155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/literalmex.com\/index.php\/wp-json\/wp\/v2\/posts?tags=1155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}